﻿{"id":24833,"date":"2026-05-08T16:00:01","date_gmt":"2026-05-08T16:00:01","guid":{"rendered":"https:\/\/librerialibera.ch\/it\/?post_type=product&p=24833"},"modified":"2026-05-08T16:00:01","modified_gmt":"2026-05-08T16:00:01","slug":"micomedicina","status":"publish","type":"product","link":"https:\/\/librerialibera.ch\/fr\/product\/micomedicina\/","title":{"rendered":"micomedicina"},"content":{"rendered":"<p>Secondo la micomedicina, i funghi sono in grado di provvedere al sostentamento e al mantenimento di un buono stato di salute e a migliorare la resistenza fisica. La micomedicina non d\u00e0 all&#8217;organismo alcuno stress, consente un migliore adattamento all&#8217;inquinamento ambientale e ha un effetto di immunomodulazione, cio\u00e8 previene sia una ridotta che una eccessiva reazione del sistema immunitario. ogni fungo ha la sua specificit\u00e0 terapeutica, ma tutti agiscono in generale sulla detossificazione e protezione epatica, sulla rimozione dei metalli pesanti accumulati nell&#8217;organismo e ottimizzano le terapie farmacologiche. Questo libro ci permette di iniziare a conoscere e approfondire lo straordinario mondo della micomedicina, oggetto di recenti studi internazionali.<\/p>","protected":false},"excerpt":{"rendered":"<p>Secondo la micomedicina, i funghi sono in grado di provvedere al sostentamento e al mantenimento di un buono stato di salute e a migliorare la resistenza fisica. La micomedicina non d\u00e0 all&#8217;organismo alcuno stress, consente un migliore adattamento all&#8217;inquinamento ambientale e ha un effetto di immunomodulazione, cio\u00e8 previene sia una ridotta che una eccessiva reazione del sistema immunitario. ogni fungo ha la sua specificit\u00e0 terapeutica, ma tutti agiscono in generale sulla detossificazione e protezione epatica, sulla rimozione dei metalli pesanti accumulati nell&#8217;organismo e ottimizzano le terapie farmacologiche. Questo libro ci permette di iniziare a conoscere e approfondire lo straordinario mondo della micomedicina, oggetto di recenti studi internazionali.<\/p>","protected":false},"featured_media":24832,"comment_status":"open","ping_status":"closed","template":"","meta":{"rank_math_lock_modified_date":false},"product_brand":[],"product_cat":[16],"product_tag":[],"class_list":{"0":"post-24833","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-librerialibera","8":"first","9":"instock","10":"taxable","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/librerialibera.ch\/fr\/wp-json\/wp\/v2\/product\/24833","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/librerialibera.ch\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/librerialibera.ch\/fr\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/librerialibera.ch\/fr\/wp-json\/wp\/v2\/comments?post=24833"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/librerialibera.ch\/fr\/wp-json\/wp\/v2\/media\/24832"}],"wp:attachment":[{"href":"https:\/\/librerialibera.ch\/fr\/wp-json\/wp\/v2\/media?parent=24833"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/librerialibera.ch\/fr\/wp-json\/wp\/v2\/product_brand?post=24833"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/librerialibera.ch\/fr\/wp-json\/wp\/v2\/product_cat?post=24833"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/librerialibera.ch\/fr\/wp-json\/wp\/v2\/product_tag?post=24833"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}